{"id":43583,"date":"2017-10-03T12:39:17","date_gmt":"2017-10-03T10:39:17","guid":{"rendered":"https:\/\/www.fondazioneluigieinaudi.it\/?p=43583"},"modified":"2020-10-18T10:12:01","modified_gmt":"2020-10-18T08:12:01","slug":"luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever","status":"publish","type":"post","link":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/","title":{"rendered":"Luigi Einaudi Foundation: more beautiful and stronger than ever"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":20329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1549],"tags":[],"class_list":["post-43583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-2017"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luigi Einaudi Foundation: more beautiful and stronger than ever - Fondazione Luigi Einaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luigi Einaudi Foundation: more beautiful and stronger than ever - Fondazione Luigi Einaudi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Luigi Einaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fleinaudi\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-03T10:39:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-18T08:12:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2017\/10\/Untitled-design-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fondazione Luigi Einaudi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fleinaudi\" \/>\n<meta name=\"twitter:site\" content=\"@fleinaudi\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fondazione Luigi Einaudi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/\"},\"author\":{\"name\":\"Fondazione Luigi Einaudi\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/person\\\/818027e442df0a4c57b6eadcf63ff0a2\"},\"headline\":\"Luigi Einaudi Foundation: more beautiful and stronger than ever\",\"datePublished\":\"2017-10-03T10:39:17+00:00\",\"dateModified\":\"2020-10-18T08:12:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/\"},\"wordCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Untitled-design-1.jpg\",\"articleSection\":[\"Events of 2017\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/\",\"name\":\"Luigi Einaudi Foundation: more beautiful and stronger than ever - Fondazione Luigi Einaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Untitled-design-1.jpg\",\"datePublished\":\"2017-10-03T10:39:17+00:00\",\"dateModified\":\"2020-10-18T08:12:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Untitled-design-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Untitled-design-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luigi Einaudi Foundation: more beautiful and stronger than ever\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/\",\"name\":\"Fondazione Luigi Einaudi ETS\",\"description\":\"Per Studi di Politica, Economia e Storia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#organization\",\"name\":\"Fondazione Luigi Einaudi ETS\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-fondazione-luigi-einaudi-ets-bianco.png\",\"contentUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-fondazione-luigi-einaudi-ets-bianco.png\",\"width\":2000,\"height\":1000,\"caption\":\"Fondazione Luigi Einaudi ETS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fleinaudi\",\"https:\\\/\\\/x.com\\\/fleinaudi\",\"https:\\\/\\\/www.instagram.com\\\/fleinaudi\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fleinaudi\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/fleinaudi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/person\\\/818027e442df0a4c57b6eadcf63ff0a2\",\"name\":\"Fondazione Luigi Einaudi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg\",\"caption\":\"Fondazione Luigi Einaudi\"},\"sameAs\":[\"itadmin@fondazioneluigieinaudi.it\"],\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/author\\\/itadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luigi Einaudi Foundation: more beautiful and stronger than ever - Fondazione Luigi Einaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/","og_locale":"en_US","og_type":"article","og_title":"Luigi Einaudi Foundation: more beautiful and stronger than ever - Fondazione Luigi Einaudi","og_url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/","og_site_name":"Fondazione Luigi Einaudi","article_publisher":"https:\/\/www.facebook.com\/fleinaudi","article_published_time":"2017-10-03T10:39:17+00:00","article_modified_time":"2020-10-18T08:12:01+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2017\/10\/Untitled-design-1.jpg","type":"image\/jpeg"}],"author":"Fondazione Luigi Einaudi","twitter_card":"summary_large_image","twitter_creator":"@fleinaudi","twitter_site":"@fleinaudi","twitter_misc":{"Written by":"Fondazione Luigi Einaudi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/#article","isPartOf":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/"},"author":{"name":"Fondazione Luigi Einaudi","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/person\/818027e442df0a4c57b6eadcf63ff0a2"},"headline":"Luigi Einaudi Foundation: more beautiful and stronger than ever","datePublished":"2017-10-03T10:39:17+00:00","dateModified":"2020-10-18T08:12:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/"},"wordCount":9,"publisher":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#organization"},"image":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2017\/10\/Untitled-design-1.jpg","articleSection":["Events of 2017"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/","url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/","name":"Luigi Einaudi Foundation: more beautiful and stronger than ever - Fondazione Luigi Einaudi","isPartOf":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/#primaryimage"},"image":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2017\/10\/Untitled-design-1.jpg","datePublished":"2017-10-03T10:39:17+00:00","dateModified":"2020-10-18T08:12:01+00:00","breadcrumb":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/#primaryimage","url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2017\/10\/Untitled-design-1.jpg","contentUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2017\/10\/Untitled-design-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/luigi-einaudi-foundation-more-beautiful-and-stronger-than-ever\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazioneluigieinaudi.it\/en\/"},{"@type":"ListItem","position":2,"name":"Luigi Einaudi Foundation: more beautiful and stronger than ever"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#website","url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/","name":"Fondazione Luigi Einaudi ETS","description":"Per Studi di Politica, Economia e Storia","publisher":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazioneluigieinaudi.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#organization","name":"Fondazione Luigi Einaudi ETS","url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2022\/05\/logo-fondazione-luigi-einaudi-ets-bianco.png","contentUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2022\/05\/logo-fondazione-luigi-einaudi-ets-bianco.png","width":2000,"height":1000,"caption":"Fondazione Luigi Einaudi ETS"},"image":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fleinaudi","https:\/\/x.com\/fleinaudi","https:\/\/www.instagram.com\/fleinaudi","https:\/\/www.linkedin.com\/company\/fleinaudi","https:\/\/www.youtube.com\/c\/fleinaudi"]},{"@type":"Person","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/person\/818027e442df0a4c57b6eadcf63ff0a2","name":"Fondazione Luigi Einaudi","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2016\/08\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg","url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2016\/08\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg","contentUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2016\/08\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg","caption":"Fondazione Luigi Einaudi"},"sameAs":["itadmin@fondazioneluigieinaudi.it"],"url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/author\/itadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/posts\/43583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/comments?post=43583"}],"version-history":[{"count":1,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/posts\/43583\/revisions"}],"predecessor-version":[{"id":43584,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/posts\/43583\/revisions\/43584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/media\/20329"}],"wp:attachment":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/media?parent=43583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/categories?post=43583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/tags?post=43583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}