{"id":39009,"date":"2020-04-15T17:00:40","date_gmt":"2020-04-15T15:00:40","guid":{"rendered":"https:\/\/www.fondazioneluigieinaudi.it\/?p=39009"},"modified":"2020-05-03T18:52:45","modified_gmt":"2020-05-03T16:52:45","slug":"live-with-antonio-tajani-fleathome-tostartagain","status":"publish","type":"post","link":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/","title":{"rendered":"Live with Antonio Tajani #FLEatHome #tostartagain"},"content":{"rendered":"<p>#FLEatHome returns to give voice to the political leaders of the main Italian parties.<\/p>\n<p>Today with the live web presence of Antonio Tajani, illustrating\u00a0his #tostartagain recipe.<\/p>\n<p>Tajani will answer questions from viewers on various topics: ESM, the liberal world, the economic crisis and ravenous bureaucracy.<\/p>\n<p><iframe loading=\"lazy\" title=\"#laFLEacasatua \u2013 Diretta con Antonio Tajani, #perRipartire\" width=\"1778\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/Sqi9d402w6k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>#FLEatHome returns to give voice to the political leaders of the main Italian parties. Today with the live web presence of Antonio Tajani, illustrating\u00a0his #tostartagain recipe. Tajani will answer questions from viewers on various topics: ESM, the liberal world, the economic crisis and ravenous bureaucracy.<\/p>\n","protected":false},"author":224,"featured_media":38652,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1091],"tags":[],"class_list":["post-39009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-2020"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Live with Antonio Tajani #FLEatHome #tostartagain - Fondazione Luigi Einaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Live with Antonio Tajani #FLEatHome #tostartagain - Fondazione Luigi Einaudi\" \/>\n<meta property=\"og:description\" content=\"#FLEatHome returns to give voice to the political leaders of the main Italian parties. Today with the live web presence of Antonio Tajani, illustrating\u00a0his #tostartagain recipe. Tajani will answer questions from viewers on various topics: ESM, the liberal world, the economic crisis and ravenous bureaucracy.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Luigi Einaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fleinaudi\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T15:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-03T16:52:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/04\/lafleacasatua-diretta-tajani-per-ripartire-15042020.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marco Cruciani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fleinaudi\" \/>\n<meta name=\"twitter:site\" content=\"@fleinaudi\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Cruciani\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/\"},\"author\":{\"name\":\"Marco Cruciani\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/person\\\/ea3481988c39cdb0e8f4cb934e3d8c7a\"},\"headline\":\"Live with Antonio Tajani #FLEatHome #tostartagain\",\"datePublished\":\"2020-04-15T15:00:40+00:00\",\"dateModified\":\"2020-05-03T16:52:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/\"},\"wordCount\":59,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lafleacasatua-diretta-tajani-per-ripartire-15042020.png\",\"articleSection\":[\"Events of 2020\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/\",\"name\":\"Live with Antonio Tajani #FLEatHome #tostartagain - Fondazione Luigi Einaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lafleacasatua-diretta-tajani-per-ripartire-15042020.png\",\"datePublished\":\"2020-04-15T15:00:40+00:00\",\"dateModified\":\"2020-05-03T16:52:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lafleacasatua-diretta-tajani-per-ripartire-15042020.png\",\"contentUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/lafleacasatua-diretta-tajani-per-ripartire-15042020.png\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/live-with-antonio-tajani-fleathome-tostartagain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Live with Antonio Tajani #FLEatHome #tostartagain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/\",\"name\":\"Fondazione Luigi Einaudi ETS\",\"description\":\"Per Studi di Politica, Economia e Storia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#organization\",\"name\":\"Fondazione Luigi Einaudi ETS\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-fondazione-luigi-einaudi-ets-bianco.png\",\"contentUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-fondazione-luigi-einaudi-ets-bianco.png\",\"width\":2000,\"height\":1000,\"caption\":\"Fondazione Luigi Einaudi ETS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fleinaudi\",\"https:\\\/\\\/x.com\\\/fleinaudi\",\"https:\\\/\\\/www.instagram.com\\\/fleinaudi\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fleinaudi\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/fleinaudi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/person\\\/ea3481988c39cdb0e8f4cb934e3d8c7a\",\"name\":\"Marco Cruciani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/marco-cruciani-150x150.jpg\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/marco-cruciani-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/marco-cruciani-150x150.jpg\",\"caption\":\"Marco Cruciani\"},\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/author\\\/marco-cruciani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Live with Antonio Tajani #FLEatHome #tostartagain - Fondazione Luigi Einaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/","og_locale":"en_US","og_type":"article","og_title":"Live with Antonio Tajani #FLEatHome #tostartagain - Fondazione Luigi Einaudi","og_description":"#FLEatHome returns to give voice to the political leaders of the main Italian parties. Today with the live web presence of Antonio Tajani, illustrating\u00a0his #tostartagain recipe. Tajani will answer questions from viewers on various topics: ESM, the liberal world, the economic crisis and ravenous bureaucracy.","og_url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/","og_site_name":"Fondazione Luigi Einaudi","article_publisher":"https:\/\/www.facebook.com\/fleinaudi","article_published_time":"2020-04-15T15:00:40+00:00","article_modified_time":"2020-05-03T16:52:45+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/04\/lafleacasatua-diretta-tajani-per-ripartire-15042020.png","type":"image\/png"}],"author":"Marco Cruciani","twitter_card":"summary_large_image","twitter_creator":"@fleinaudi","twitter_site":"@fleinaudi","twitter_misc":{"Written by":"Marco Cruciani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/#article","isPartOf":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/"},"author":{"name":"Marco Cruciani","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/person\/ea3481988c39cdb0e8f4cb934e3d8c7a"},"headline":"Live with Antonio Tajani #FLEatHome #tostartagain","datePublished":"2020-04-15T15:00:40+00:00","dateModified":"2020-05-03T16:52:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/"},"wordCount":59,"publisher":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#organization"},"image":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/04\/lafleacasatua-diretta-tajani-per-ripartire-15042020.png","articleSection":["Events of 2020"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/","url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/","name":"Live with Antonio Tajani #FLEatHome #tostartagain - Fondazione Luigi Einaudi","isPartOf":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/#primaryimage"},"image":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/04\/lafleacasatua-diretta-tajani-per-ripartire-15042020.png","datePublished":"2020-04-15T15:00:40+00:00","dateModified":"2020-05-03T16:52:45+00:00","breadcrumb":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/#primaryimage","url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/04\/lafleacasatua-diretta-tajani-per-ripartire-15042020.png","contentUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/04\/lafleacasatua-diretta-tajani-per-ripartire-15042020.png","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/live-with-antonio-tajani-fleathome-tostartagain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazioneluigieinaudi.it\/en\/"},{"@type":"ListItem","position":2,"name":"Live with Antonio Tajani #FLEatHome #tostartagain"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#website","url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/","name":"Fondazione Luigi Einaudi ETS","description":"Per Studi di Politica, Economia e Storia","publisher":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazioneluigieinaudi.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#organization","name":"Fondazione Luigi Einaudi ETS","url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2022\/05\/logo-fondazione-luigi-einaudi-ets-bianco.png","contentUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2022\/05\/logo-fondazione-luigi-einaudi-ets-bianco.png","width":2000,"height":1000,"caption":"Fondazione Luigi Einaudi ETS"},"image":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fleinaudi","https:\/\/x.com\/fleinaudi","https:\/\/www.instagram.com\/fleinaudi","https:\/\/www.linkedin.com\/company\/fleinaudi","https:\/\/www.youtube.com\/c\/fleinaudi"]},{"@type":"Person","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/person\/ea3481988c39cdb0e8f4cb934e3d8c7a","name":"Marco Cruciani","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2023\/03\/marco-cruciani-150x150.jpg","url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2023\/03\/marco-cruciani-150x150.jpg","contentUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2023\/03\/marco-cruciani-150x150.jpg","caption":"Marco Cruciani"},"url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/author\/marco-cruciani\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/posts\/39009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/users\/224"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/comments?post=39009"}],"version-history":[{"count":2,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/posts\/39009\/revisions"}],"predecessor-version":[{"id":39029,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/posts\/39009\/revisions\/39029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/media\/38652"}],"wp:attachment":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/media?parent=39009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/categories?post=39009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/tags?post=39009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}