{"id":38377,"date":"2020-02-26T16:44:08","date_gmt":"2020-02-26T15:44:08","guid":{"rendered":"https:\/\/www.fondazioneluigieinaudi.it\/?p=38377"},"modified":"2020-04-04T23:38:58","modified_gmt":"2020-04-04T22:38:58","slug":"reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve","status":"publish","type":"post","link":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/","title":{"rendered":"Reduction in the number of Members of Parliament and \u2018Bonafede Reform\u2019. Book presentation: \u201cLEALI ALL\u2019ITALIA\u201d by Davide Giacalone #STANCHIDIPAGARE \u2013 EVENT POSTPONED"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":35786,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1091],"tags":[],"class_list":["post-38377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-2020"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reduction in the number of Members of Parliament and \u2018Bonafede Reform\u2019. Book presentation: \u201cLEALI ALL\u2019ITALIA\u201d by Davide Giacalone #STANCHIDIPAGARE \u2013 EVENT POSTPONED - Fondazione Luigi Einaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reduction in the number of Members of Parliament and \u2018Bonafede Reform\u2019. Book presentation: \u201cLEALI ALL\u2019ITALIA\u201d by Davide Giacalone #STANCHIDIPAGARE \u2013 EVENT POSTPONED - Fondazione Luigi Einaudi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Luigi Einaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fleinaudi\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-26T15:44:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-04T22:38:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/02\/26022020-taglio-parlamenti-riforma-bonafede-stanchidipagare.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fondazione Luigi Einaudi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fleinaudi\" \/>\n<meta name=\"twitter:site\" content=\"@fleinaudi\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fondazione Luigi Einaudi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/\"},\"author\":{\"name\":\"Fondazione Luigi Einaudi\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/person\\\/818027e442df0a4c57b6eadcf63ff0a2\"},\"headline\":\"Reduction in the number of Members of Parliament and \u2018Bonafede Reform\u2019. Book presentation: \u201cLEALI ALL\u2019ITALIA\u201d by Davide Giacalone #STANCHIDIPAGARE \u2013 EVENT POSTPONED\",\"datePublished\":\"2020-02-26T15:44:08+00:00\",\"dateModified\":\"2020-04-04T22:38:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/\"},\"wordCount\":22,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/26022020-taglio-parlamenti-riforma-bonafede-stanchidipagare.png\",\"articleSection\":[\"Events of 2020\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/\",\"name\":\"Reduction in the number of Members of Parliament and \u2018Bonafede Reform\u2019. Book presentation: \u201cLEALI ALL\u2019ITALIA\u201d by Davide Giacalone #STANCHIDIPAGARE \u2013 EVENT POSTPONED - Fondazione Luigi Einaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/26022020-taglio-parlamenti-riforma-bonafede-stanchidipagare.png\",\"datePublished\":\"2020-02-26T15:44:08+00:00\",\"dateModified\":\"2020-04-04T22:38:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/26022020-taglio-parlamenti-riforma-bonafede-stanchidipagare.png\",\"contentUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/26022020-taglio-parlamenti-riforma-bonafede-stanchidipagare.png\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reduction in the number of Members of Parliament and \u2018Bonafede Reform\u2019. Book presentation: \u201cLEALI ALL\u2019ITALIA\u201d by Davide Giacalone #STANCHIDIPAGARE \u2013 EVENT POSTPONED\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/\",\"name\":\"Fondazione Luigi Einaudi ETS\",\"description\":\"Per Studi di Politica, Economia e Storia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#organization\",\"name\":\"Fondazione Luigi Einaudi ETS\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-fondazione-luigi-einaudi-ets-bianco.png\",\"contentUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-fondazione-luigi-einaudi-ets-bianco.png\",\"width\":2000,\"height\":1000,\"caption\":\"Fondazione Luigi Einaudi ETS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fleinaudi\",\"https:\\\/\\\/x.com\\\/fleinaudi\",\"https:\\\/\\\/www.instagram.com\\\/fleinaudi\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fleinaudi\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/fleinaudi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/#\\\/schema\\\/person\\\/818027e442df0a4c57b6eadcf63ff0a2\",\"name\":\"Fondazione Luigi Einaudi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg\",\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg\",\"caption\":\"Fondazione Luigi Einaudi\"},\"sameAs\":[\"itadmin@fondazioneluigieinaudi.it\"],\"url\":\"https:\\\/\\\/www.fondazioneluigieinaudi.it\\\/en\\\/author\\\/itadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reduction in the number of Members of Parliament and \u2018Bonafede Reform\u2019. Book presentation: \u201cLEALI ALL\u2019ITALIA\u201d by Davide Giacalone #STANCHIDIPAGARE \u2013 EVENT POSTPONED - Fondazione Luigi Einaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/","og_locale":"en_US","og_type":"article","og_title":"Reduction in the number of Members of Parliament and \u2018Bonafede Reform\u2019. Book presentation: \u201cLEALI ALL\u2019ITALIA\u201d by Davide Giacalone #STANCHIDIPAGARE \u2013 EVENT POSTPONED - Fondazione Luigi Einaudi","og_url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/","og_site_name":"Fondazione Luigi Einaudi","article_publisher":"https:\/\/www.facebook.com\/fleinaudi","article_published_time":"2020-02-26T15:44:08+00:00","article_modified_time":"2020-04-04T22:38:58+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/02\/26022020-taglio-parlamenti-riforma-bonafede-stanchidipagare.png","type":"image\/png"}],"author":"Fondazione Luigi Einaudi","twitter_card":"summary_large_image","twitter_creator":"@fleinaudi","twitter_site":"@fleinaudi","twitter_misc":{"Written by":"Fondazione Luigi Einaudi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/#article","isPartOf":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/"},"author":{"name":"Fondazione Luigi Einaudi","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/person\/818027e442df0a4c57b6eadcf63ff0a2"},"headline":"Reduction in the number of Members of Parliament and \u2018Bonafede Reform\u2019. Book presentation: \u201cLEALI ALL\u2019ITALIA\u201d by Davide Giacalone #STANCHIDIPAGARE \u2013 EVENT POSTPONED","datePublished":"2020-02-26T15:44:08+00:00","dateModified":"2020-04-04T22:38:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/"},"wordCount":22,"publisher":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#organization"},"image":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/02\/26022020-taglio-parlamenti-riforma-bonafede-stanchidipagare.png","articleSection":["Events of 2020"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/","url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/","name":"Reduction in the number of Members of Parliament and \u2018Bonafede Reform\u2019. Book presentation: \u201cLEALI ALL\u2019ITALIA\u201d by Davide Giacalone #STANCHIDIPAGARE \u2013 EVENT POSTPONED - Fondazione Luigi Einaudi","isPartOf":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/#primaryimage"},"image":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/02\/26022020-taglio-parlamenti-riforma-bonafede-stanchidipagare.png","datePublished":"2020-02-26T15:44:08+00:00","dateModified":"2020-04-04T22:38:58+00:00","breadcrumb":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/#primaryimage","url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/02\/26022020-taglio-parlamenti-riforma-bonafede-stanchidipagare.png","contentUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2020\/02\/26022020-taglio-parlamenti-riforma-bonafede-stanchidipagare.png","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/reduction-in-the-number-of-members-of-parliament-and-bonafede-reform-book-presentation-leali-allitalia-by-davide-giacalone-stanchidipagare-eve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazioneluigieinaudi.it\/en\/"},{"@type":"ListItem","position":2,"name":"Reduction in the number of Members of Parliament and \u2018Bonafede Reform\u2019. Book presentation: \u201cLEALI ALL\u2019ITALIA\u201d by Davide Giacalone #STANCHIDIPAGARE \u2013 EVENT POSTPONED"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#website","url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/","name":"Fondazione Luigi Einaudi ETS","description":"Per Studi di Politica, Economia e Storia","publisher":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazioneluigieinaudi.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#organization","name":"Fondazione Luigi Einaudi ETS","url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2022\/05\/logo-fondazione-luigi-einaudi-ets-bianco.png","contentUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2022\/05\/logo-fondazione-luigi-einaudi-ets-bianco.png","width":2000,"height":1000,"caption":"Fondazione Luigi Einaudi ETS"},"image":{"@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fleinaudi","https:\/\/x.com\/fleinaudi","https:\/\/www.instagram.com\/fleinaudi","https:\/\/www.linkedin.com\/company\/fleinaudi","https:\/\/www.youtube.com\/c\/fleinaudi"]},{"@type":"Person","@id":"https:\/\/www.fondazioneluigieinaudi.it\/en\/#\/schema\/person\/818027e442df0a4c57b6eadcf63ff0a2","name":"Fondazione Luigi Einaudi","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2016\/08\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg","url":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2016\/08\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg","contentUrl":"https:\/\/www.fondazioneluigieinaudi.it\/wp-content\/uploads\/2016\/08\/LOGO-positivo-INTERO_onlus-Copia-Copia-150x150.jpg","caption":"Fondazione Luigi Einaudi"},"sameAs":["itadmin@fondazioneluigieinaudi.it"],"url":"https:\/\/www.fondazioneluigieinaudi.it\/en\/author\/itadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/posts\/38377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/comments?post=38377"}],"version-history":[{"count":0,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/posts\/38377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/media\/35786"}],"wp:attachment":[{"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/media?parent=38377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/categories?post=38377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazioneluigieinaudi.it\/en\/wp-json\/wp\/v2\/tags?post=38377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}